{"id":2970,"date":"2024-03-13T14:49:33","date_gmt":"2024-03-13T13:49:33","guid":{"rendered":"https:\/\/www.artoisplastiques.fr\/qualitat-sicherheit-umwelt\/"},"modified":"2024-12-11T16:41:13","modified_gmt":"2024-12-11T15:41:13","slug":"qualitat-sicherheit-umwelt","status":"publish","type":"page","link":"https:\/\/www.artoisplastiques.fr\/de\/qualitat-sicherheit-umwelt\/","title":{"rendered":"Qualit\u00e4t Sicherheit Umwelt"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2970\" class=\"elementor elementor-2970 elementor-38\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db1aa9b e-flex e-con-boxed e-con e-parent\" data-id=\"db1aa9b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc65e40 elementor-widget elementor-widget-heading\" data-id=\"cc65e40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Qualit\u00e4t Sicherheit Umwelt<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9072110 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9072110\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Bei Artois Plastiques sind wir davon \u00fcberzeugt, dass Qualit\u00e4t, Sicherheit und Umweltschutz die Grundlagen f\u00fcr ein nachhaltiges und leistungsstarkes Unternehmen sind. Aus diesem Grund haben wir strenge Richtlinien und innovative Prozesse eingef\u00fchrt, um in jeder Phase des Produktionsprozesses Spitzenleistungen zu gew\u00e4hrleisten. <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fac0ee2 e-flex e-con-boxed e-con e-parent\" data-id=\"fac0ee2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-47a085c e-con-full e-flex e-con e-child\" data-id=\"47a085c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-32f18b1 e-con-full e-flex e-con e-child\" data-id=\"32f18b1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b07c2a9 elementor-widget elementor-widget-raven-image\" data-id=\"b07c2a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/AdobeStock_386408319-scaled.jpeg\" class=\"attachment-full size-full wp-image-2977\" alt=\"Outils de contr\u00f4le pour am\u00e9liorer l&#039;usinage piece plastique\" srcset=\"https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/AdobeStock_386408319-scaled.jpeg 2560w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/AdobeStock_386408319-300x200.jpeg 300w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/AdobeStock_386408319-1024x683.jpeg 1024w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/AdobeStock_386408319-768x512.jpeg 768w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/AdobeStock_386408319-1536x1024.jpeg 1536w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/AdobeStock_386408319-2048x1365.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4770cc6 e-con-full e-flex e-con e-child\" data-id=\"4770cc6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06a088e elementor-widget elementor-widget-heading\" data-id=\"06a088e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qualit\u00e4t im Mittelpunkt\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24aae2c elementor-widget elementor-widget-text-editor\" data-id=\"24aae2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Ma\u00dfgeschneiderte Produkte:<\/b> <span style=\"font-weight: 400;\">Wir arbeiten eng mit unseren Kunden zusammen, um Kunststoffl\u00f6sungen zu entwerfen, die perfekt auf ihre spezifischen Bed\u00fcrfnisse zugeschnitten sind.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Streng ausgew\u00e4hlte Rohstoffe :<\/b><span style=\"font-weight: 400;\"> Wir bevorzugen zuverl\u00e4ssige Lieferanten und stellen sicher, dass unsere Rohstoffe den geltenden Normen entsprechen. Insbesondere bei food grades und detektierbaren VMX-Kunststoffen. <\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Strenge Qualit\u00e4tskontrolle:<\/b> <span style=\"font-weight: 400;\">Vom Entwurf bis zur Auslieferung unterliegt jeder Produktionsschritt strengen Qualit\u00e4tskontrollen, um die hervorragende Qualit\u00e4t unserer Produkte zu gew\u00e4hrleisten.<\/span><\/li>\n<li><b>ISO 9001-Zertifizierung:<\/b> <span style=\"font-weight: 400;\">Unser Qualit\u00e4tsmanagementsystem, das nach ISO 9001 zertifiziert ist, belegt unser Engagement f\u00fcr die Bereitstellung von Produkten und Dienstleistungen, die den Anforderungen unserer Kunden und den geltenden Vorschriften entsprechen.<\/span><\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5bd1847 e-flex e-con-boxed e-con e-parent\" data-id=\"5bd1847\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c4298f5 e-con-full e-flex e-con e-child\" data-id=\"c4298f5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1608c9 elementor-widget elementor-widget-heading\" data-id=\"d1608c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Sicherheit als oberste Priorit\u00e4t\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8018fb2 elementor-widget elementor-widget-text-editor\" data-id=\"8018fb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Gesundheit und Sicherheit unserer Mitarbeiterinnen und Mitarbeiter:<\/b> <span style=\"font-weight: 400;\">Wir tun alles, um eine sichere und gesunde Arbeitsumgebung f\u00fcr alle unsere Mitarbeiterinnen und Mitarbeiter zu gew\u00e4hrleisten.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Pers\u00f6nliche Schutzausr\u00fcstung:<\/b> <span style=\"font-weight: 400;\">Wir stellen unseren Mitarbeitern die notwendige pers\u00f6nliche Schutzausr\u00fcstung zur Verf\u00fcgung.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Schulung und Sensibilisierung:<\/b> <span style=\"font-weight: 400;\">Wir f\u00fchren regelm\u00e4\u00dfig Schulungen durch, um unsere Teams f\u00fcr Sicherheitsrisiken und bew\u00e4hrte Praktiken zu sensibilisieren.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Unfallverh\u00fctung :<\/b> <span style=\"font-weight: 400;\">Wir f\u00fchren regelm\u00e4\u00dfig Risikoanalysen durch und leiten Korrekturma\u00dfnahmen ein, um Unf\u00e4llen vorzubeugen.<\/span><\/li>\n<li><b>Baustelle Ergonomie am Arbeitsplatz<\/b><span style=\"font-weight: 400;\"> : Um den Komfort und die Gesundheit unserer Mitarbeiter zu optimieren, haben wir die Expertise eines auf Ergonomie spezialisierten B\u00fcros in Anspruch genommen, um geeignetere Arbeitspl\u00e4tze einzurichten. Durch neue ergonomische Ausstattungen wollen wir Muskel-Skelett-Erkrankungen vorbeugen und die Lebensqualit\u00e4t am Arbeitsplatz verbessern.  <\/span><\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ac0421 e-con-full e-flex e-con e-child\" data-id=\"8ac0421\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-584c67a elementor-widget elementor-widget-raven-image\" data-id=\"584c67a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/AP_085-min-scaled.jpg\" class=\"attachment-full size-full wp-image-2971\" alt=\"\" srcset=\"https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/AP_085-min-scaled.jpg 2560w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/AP_085-min-300x200.jpg 300w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/AP_085-min-1024x683.jpg 1024w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/AP_085-min-768x512.jpg 768w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/AP_085-min-1536x1024.jpg 1536w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/AP_085-min-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b4228fd e-con-full e-flex e-con e-child\" data-id=\"b4228fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9ca5cec e-flex e-con-boxed e-con e-parent\" data-id=\"9ca5cec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f91e0c3 e-con-full e-flex e-con e-child\" data-id=\"f91e0c3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-43dc544 e-con-full e-flex e-con e-child\" data-id=\"43dc544\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5fd4dbc e-con-full e-flex e-con e-child\" data-id=\"5fd4dbc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a38c52 elementor-widget elementor-widget-heading\" data-id=\"8a38c52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Umweltfreundlichkeit, ein starkes Engagement\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff70fa5 elementor-widget elementor-widget-text-editor\" data-id=\"ff70fa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Reduzierung unseres \u00f6kologischen Fu\u00dfabdrucks:<\/b> <span style=\"font-weight: 400;\">Wir setzen konkrete Ma\u00dfnahmen um, um unseren Energie- und Wasserverbrauch sowie die Abfallproduktion zu reduzieren.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Recycling:<\/b> <span style=\"font-weight: 400;\">Wir verwerten so viel wie m\u00f6glich von unserem Abfall und f\u00f6rdern das Recycling unserer Produkte am Ende ihres Lebenszyklus.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u00d6kologisch gestaltete Produkte:<\/b> <span style=\"font-weight: 400;\">Wir bevorzugen recycelbare Materialien und optimieren die Gestaltung unserer Produkte, um ihre Auswirkungen auf die Umwelt zu verringern.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Nachhaltige Entwicklung:<\/b> <span style=\"font-weight: 400;\">Wir setzen uns f\u00fcr eine nachhaltige Entwicklung ein und investieren in innovative Projekte, um unsere Auswirkungen auf die Umwelt zu verringern.<\/span><\/li>\n<li><b>ISO 14001-Zertifizierung:<\/b> <span style=\"font-weight: 400;\">Unser Umweltmanagementsystem, das nach ISO 14001 zertifiziert ist, zeugt von unserem Engagement, die Umweltauswirkungen unserer Aktivit\u00e4ten unter Kontrolle zu halten.<\/span><\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0eae4a7 e-flex e-con-boxed e-con e-parent\" data-id=\"0eae4a7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e36852c e-con-full e-flex e-con e-child\" data-id=\"e36852c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7087a93 elementor-widget elementor-widget-heading\" data-id=\"7087a93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kontinuierliche Verbesserung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc23eeb elementor-widget elementor-widget-text-editor\" data-id=\"cc23eeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b><i>Die in unserer Einrichtung eingesetzten Instrumente zur kontinuierlichen Verbesserung :<\/i><\/b><\/p>\n<p><b><i>5 S :<\/i><\/b><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">SEIRI &#8211; Entr\u00fcmpeln: Unn\u00f6tiges entfernen, um die wesentlichen Gegenst\u00e4nde am Arbeitsplatz zu behalten.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">SEITON &#8211; Aufr\u00e4umen: Ordnen Sie n\u00fctzliche Gegenst\u00e4nde nach H\u00e4ufigkeit, Verwendung und Handhabbarkeit. Machen Sie die Standorte offensichtlich. <\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">SEISO &#8211; Reinigen: Reinigen, inspizieren und Anomalien erkennen.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">SEIKETSU &#8211; Standardisieren: Erstellen von Benchmarks (typisches Foto des Idealzustands eines Arbeitsplatzes).<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">SHITSUKE &#8211; Nachhaltig: Die eingef\u00fchrten Regeln einhalten und den Standard kontinuierlich verbessern (5S-Audit).<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">1 Baustelle der technischen B\u00fcros, die ab September 2011 mit APAF l\u00e4uft: P\u00f4le d&#8217;Excellence Plasturgie.<\/span><\/p>\n<\/p>\n<p><b>QRQC<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Wir versammeln das technische Team w\u00f6chentlich, um \u00fcber m\u00f6gliche Probleme zu sprechen, mit denen sie konfrontiert sind, aber auch, um einen gem\u00fctlichen Moment zu verbringen.<\/span><\/p>\n<\/p>\n<p><b><i>LEAN MANUFACTURING :<\/i><\/b><\/p>\n<p><span style=\"font-weight: 400;\">Lean Manufacturing ist in unserer Unternehmenskultur verankert. Indem wir unsere Teams aktiv einbeziehen, arbeiten wir gemeinsam an der Beseitigung der 7 Verschwendungen (\u00dcberproduktion, Wartezeiten, Transport, Fehler, Inventar, unn\u00f6tige Bewegungen und unn\u00f6tige Verarbeitung). Diese Ma\u00dfnahmen erm\u00f6glichen es uns, unsere Leistung kontinuierlich zu verbessern und den Bed\u00fcrfnissen unserer Kunden immer besser gerecht zu werden.  <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-def2c6c e-con-full e-flex e-con e-child\" data-id=\"def2c6c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae31737 elementor-widget elementor-widget-raven-image\" data-id=\"ae31737\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/amelioration-2-scaled.jpg\" class=\"attachment-full size-full wp-image-2975\" alt=\"\" srcset=\"https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/amelioration-2-scaled.jpg 2560w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/amelioration-2-300x200.jpg 300w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/amelioration-2-1024x683.jpg 1024w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/amelioration-2-768x512.jpg 768w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/amelioration-2-1536x1024.jpg 1536w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/11\/amelioration-2-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e68e532 e-con-full e-flex e-con e-child\" data-id=\"e68e532\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-df4d160 e-flex e-con-boxed e-con e-parent\" data-id=\"df4d160\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-aca0f78 e-con-full e-flex e-con e-child\" data-id=\"aca0f78\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-479a126 elementor-widget elementor-widget-heading\" data-id=\"479a126\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schlussfolgerung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6453331 elementor-widget elementor-widget-text-editor\" data-id=\"6453331\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Wenn Sie sich f\u00fcr Artois Plastiques entscheiden, w\u00e4hlen Sie einen Partner, der sich f\u00fcr kontinuierliche Verbesserung und nachhaltige Entwicklung einsetzt. Dank unserer Zertifizierungen ISO 9001 und 14001 profitieren Sie von qualitativ hochwertigen Produkten und Dienstleistungen, die mit Respekt f\u00fcr die Umwelt und die Menschen hergestellt werden. <\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c79c583 e-flex e-con-boxed e-con e-parent\" data-id=\"c79c583\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-50b7afa e-con-full e-flex e-con e-child\" data-id=\"50b7afa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe731ad elementor-widget elementor-widget-heading\" data-id=\"fe731ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ein Projekt?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c32afad elementor-widget elementor-widget-heading\" data-id=\"c32afad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Unsere Techniker beantworten gerne Ihre Fragen.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ff8faa e-con-full e-flex e-con e-child\" data-id=\"6ff8faa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-edcd568 contact-btn elementor-widget elementor-widget-raven-image\" data-id=\"edcd568\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"482\" height=\"107\" src=\"https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/10\/Bouton-Contact.png\" class=\"attachment-full size-full wp-image-2657\" alt=\"\" srcset=\"https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/10\/Bouton-Contact.png 482w, https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/10\/Bouton-Contact-300x67.png 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Qualit\u00e4t Sicherheit Umwelt Bei Artois Plastiques sind wir davon \u00fcberzeugt, dass Qualit\u00e4t, Sicherheit und Umweltschutz die Grundlagen f\u00fcr ein nachhaltiges und leistungsstarkes Unternehmen sind. Aus diesem Grund haben wir strenge Richtlinien und innovative Prozesse eingef\u00fchrt, um in jeder Phase des Produktionsprozesses Spitzenleistungen zu gew\u00e4hrleisten. Qualit\u00e4t im Mittelpunkt Ma\u00dfgeschneiderte Produkte: Wir arbeiten eng mit unseren Kunden [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":58,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":12,"footnotes":""},"class_list":["post-2970","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qualit\u00e4t Sicherheit Umwelt - Artois Plastiques<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.artoisplastiques.fr\/de\/qualitat-sicherheit-umwelt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qualit\u00e4t Sicherheit Umwelt - Artois Plastiques\" \/>\n<meta property=\"og:description\" content=\"Qualit\u00e4t Sicherheit Umwelt Bei Artois Plastiques sind wir davon \u00fcberzeugt, dass Qualit\u00e4t, Sicherheit und Umweltschutz die Grundlagen f\u00fcr ein nachhaltiges und leistungsstarkes Unternehmen sind. Aus diesem Grund haben wir strenge Richtlinien und innovative Prozesse eingef\u00fchrt, um in jeder Phase des Produktionsprozesses Spitzenleistungen zu gew\u00e4hrleisten. Qualit\u00e4t im Mittelpunkt Ma\u00dfgeschneiderte Produkte: Wir arbeiten eng mit unseren Kunden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.artoisplastiques.fr\/de\/qualitat-sicherheit-umwelt\/\" \/>\n<meta property=\"og:site_name\" content=\"Artois Plastiques\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-11T15:41:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/03\/artois-footer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"315\" \/>\n\t<meta property=\"og:image:height\" content=\"116\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.artoisplastiques.fr\\\/de\\\/qualitat-sicherheit-umwelt\\\/\",\"url\":\"https:\\\/\\\/www.artoisplastiques.fr\\\/de\\\/qualitat-sicherheit-umwelt\\\/\",\"name\":\"Qualit\u00e4t Sicherheit Umwelt - Artois Plastiques\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.artoisplastiques.fr\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.artoisplastiques.fr\\\/de\\\/qualitat-sicherheit-umwelt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.artoisplastiques.fr\\\/de\\\/qualitat-sicherheit-umwelt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.artoisplastiques.fr\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/artois-footer.jpg\",\"datePublished\":\"2024-03-13T13:49:33+00:00\",\"dateModified\":\"2024-12-11T15:41:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.artoisplastiques.fr\\\/de\\\/qualitat-sicherheit-umwelt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.artoisplastiques.fr\\\/de\\\/qualitat-sicherheit-umwelt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.artoisplastiques.fr\\\/de\\\/qualitat-sicherheit-umwelt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.artoisplastiques.fr\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/artois-footer.jpg\",\"contentUrl\":\"https:\\\/\\\/www.artoisplastiques.fr\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/artois-footer.jpg\",\"width\":315,\"height\":116,\"caption\":\"logo artois plastiques footer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.artoisplastiques.fr\\\/de\\\/qualitat-sicherheit-umwelt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.artoisplastiques.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qualit\u00e4t Sicherheit Umwelt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.artoisplastiques.fr\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.artoisplastiques.fr\\\/de\\\/\",\"name\":\"Artois Plastiques\",\"description\":\"ARTOIS PLASTIQUES VOTRE PARTENAIRE POUR LA R\u00c9ALISATION DE PI\u00c8CES EN PLASTIQUES TECHNIQUES\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.artoisplastiques.fr\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qualit\u00e4t Sicherheit Umwelt - Artois Plastiques","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.artoisplastiques.fr\/de\/qualitat-sicherheit-umwelt\/","og_locale":"de_DE","og_type":"article","og_title":"Qualit\u00e4t Sicherheit Umwelt - Artois Plastiques","og_description":"Qualit\u00e4t Sicherheit Umwelt Bei Artois Plastiques sind wir davon \u00fcberzeugt, dass Qualit\u00e4t, Sicherheit und Umweltschutz die Grundlagen f\u00fcr ein nachhaltiges und leistungsstarkes Unternehmen sind. Aus diesem Grund haben wir strenge Richtlinien und innovative Prozesse eingef\u00fchrt, um in jeder Phase des Produktionsprozesses Spitzenleistungen zu gew\u00e4hrleisten. Qualit\u00e4t im Mittelpunkt Ma\u00dfgeschneiderte Produkte: Wir arbeiten eng mit unseren Kunden [&hellip;]","og_url":"https:\/\/www.artoisplastiques.fr\/de\/qualitat-sicherheit-umwelt\/","og_site_name":"Artois Plastiques","article_modified_time":"2024-12-11T15:41:13+00:00","og_image":[{"width":315,"height":116,"url":"https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/03\/artois-footer.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.artoisplastiques.fr\/de\/qualitat-sicherheit-umwelt\/","url":"https:\/\/www.artoisplastiques.fr\/de\/qualitat-sicherheit-umwelt\/","name":"Qualit\u00e4t Sicherheit Umwelt - Artois Plastiques","isPartOf":{"@id":"https:\/\/www.artoisplastiques.fr\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.artoisplastiques.fr\/de\/qualitat-sicherheit-umwelt\/#primaryimage"},"image":{"@id":"https:\/\/www.artoisplastiques.fr\/de\/qualitat-sicherheit-umwelt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/03\/artois-footer.jpg","datePublished":"2024-03-13T13:49:33+00:00","dateModified":"2024-12-11T15:41:13+00:00","breadcrumb":{"@id":"https:\/\/www.artoisplastiques.fr\/de\/qualitat-sicherheit-umwelt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.artoisplastiques.fr\/de\/qualitat-sicherheit-umwelt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.artoisplastiques.fr\/de\/qualitat-sicherheit-umwelt\/#primaryimage","url":"https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/03\/artois-footer.jpg","contentUrl":"https:\/\/www.artoisplastiques.fr\/wp-content\/uploads\/2024\/03\/artois-footer.jpg","width":315,"height":116,"caption":"logo artois plastiques footer"},{"@type":"BreadcrumbList","@id":"https:\/\/www.artoisplastiques.fr\/de\/qualitat-sicherheit-umwelt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.artoisplastiques.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Qualit\u00e4t Sicherheit Umwelt"}]},{"@type":"WebSite","@id":"https:\/\/www.artoisplastiques.fr\/de\/#website","url":"https:\/\/www.artoisplastiques.fr\/de\/","name":"Artois Plastiques","description":"ARTOIS PLASTIQUES VOTRE PARTENAIRE POUR LA R\u00c9ALISATION DE PI\u00c8CES EN PLASTIQUES TECHNIQUES","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.artoisplastiques.fr\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.artoisplastiques.fr\/de\/wp-json\/wp\/v2\/pages\/2970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.artoisplastiques.fr\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.artoisplastiques.fr\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.artoisplastiques.fr\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.artoisplastiques.fr\/de\/wp-json\/wp\/v2\/comments?post=2970"}],"version-history":[{"count":3,"href":"https:\/\/www.artoisplastiques.fr\/de\/wp-json\/wp\/v2\/pages\/2970\/revisions"}],"predecessor-version":[{"id":2980,"href":"https:\/\/www.artoisplastiques.fr\/de\/wp-json\/wp\/v2\/pages\/2970\/revisions\/2980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.artoisplastiques.fr\/de\/wp-json\/wp\/v2\/media\/58"}],"wp:attachment":[{"href":"https:\/\/www.artoisplastiques.fr\/de\/wp-json\/wp\/v2\/media?parent=2970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}